{"id":20854,"date":"2023-05-25T18:36:00","date_gmt":"2023-05-25T22:36:00","guid":{"rendered":"https:\/\/revalizesoftware.com\/rechtliches\/globaler-cookie-hinweis\/"},"modified":"2025-03-12T13:05:45","modified_gmt":"2025-03-12T17:05:45","slug":"globaler-cookie-hinweis","status":"publish","type":"page","link":"https:\/\/revalizesoftware.com\/de\/rechtliches\/globaler-cookie-hinweis\/","title":{"rendered":"Globaler Cookie-Hinweis"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"20854\" class=\"elementor elementor-20854 elementor-10833\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bca8a0e e-flex e-con-boxed e-con e-parent\" data-id=\"bca8a0e\" data-element_type=\"container\" data-e-type=\"container\" id=\"global-cookie-notice\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3917722 e-con-full e-flex e-con e-child\" data-id=\"3917722\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1fc4b73 elementor-widget elementor-widget-heading\" data-id=\"1fc4b73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Globaler Cookie-Hinweis von Revalize<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-524042e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"524042e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c286a2 elementor-widget elementor-widget-text-editor\" data-id=\"5c286a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wirksamkeitsdatum: 28. Oktober 2024<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9b6754 elementor-widget elementor-widget-text-editor\" data-id=\"a9b6754\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Revalize, Inc. (&#8220;Revalize&#8221;, &#8220;Wir&#8221;, &#8220;Uns&#8221;, &#8220;Unser&#8221;) verwendet wie viele andere Unternehmen &#8220;Cookies&#8221; und andere Tracking-Technologien (zusammenfassend als &#8220;Tracking-Technologien&#8221; bezeichnet), um unsere Dienste (&#8220;Dienste&#8221;) zu erm\u00f6glichen, zu personalisieren und zu verbessern.<\/p>\n<p>In diesem Cookie-Hinweis werden die von uns verwendeten Tracking-Technologien, die Zwecke, f\u00fcr die wir sie verwenden, und Ihre diesbez\u00fcglichen Wahlm\u00f6glichkeiten erl\u00e4utert. Weitere Informationen \u00fcber die Erfassung und Verwendung pers\u00f6nlicher Daten durch Revalize finden Sie in unserer <span style=\"color: #00bad9;\"><a style=\"color: #00bad9;\" href=\"https:\/\/revalizesoftware.com\/de\/rechtliches\/datenschutzrichtlinie\/\">Datenschutzrichtlinie<\/a><\/span>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95bc6ac elementor-widget elementor-widget-heading\" data-id=\"95bc6ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Welche Tracking-Technologien verwenden wir?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42b9f2f elementor-widget elementor-widget-text-editor\" data-id=\"42b9f2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir k\u00f6nnen die folgenden Technologien f\u00fcr die in diesem Cookie-Hinweis beschriebenen Zwecke verwenden:<\/p>\n<p>&#8220;Cookies&#8221; sind kleine Textdateien, die in Ihrem Browser abgelegt und gespeichert werden, wenn Sie eine Website besuchen, oder auf Ihrem Ger\u00e4t, wenn Sie eine App verwenden. Sie k\u00f6nnen entweder von der Website oder App, die Sie besuchen, (in diesem Fall werden sie als &#8220;Erstanbieter&#8221;-Cookies bezeichnet) oder von anderen Unternehmen (in diesem Fall werden sie als &#8220;Drittanbieter-Cookies&#8221; bezeichnet) platziert werden.<\/p>\n<p>&#8220;Pixel-Tags&#8221; (auch Beacons genannt) sind unsichtbare Grafikdateien \/ kleine Codebl\u00f6cke, die auf einer Webseite, App, E-Mail oder Werbung platziert werden und eine eindeutige Kennung enthalten und es uns erm\u00f6glichen, Benutzer bei der Bereitstellung unserer Dienste zu erkennen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc64da3 elementor-widget elementor-widget-heading\" data-id=\"cc64da3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Kategorien von Cookies<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-427e8b9 elementor-widget elementor-widget-text-editor\" data-id=\"427e8b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol>\n<li><strong>Unbedingt erforderliche Cookies.<\/strong> Diese Cookies sind f\u00fcr die Bereitstellung unserer Dienste unerl\u00e4sslich.<\/li>\n<li><strong>Pr\u00e4ferenz- und Funktionalit\u00e4ts-Cookies.<\/strong> Diese Cookies erm\u00f6glichen es unserer Website, Informationen \u00fcber Ihre Pr\u00e4ferenzen zu speichern, wie z. B. die von Ihnen gew\u00e4hlte Sprache.<\/li>\n<li><strong>Analytische Cookies.<\/strong> Diese Cookies helfen uns zu verstehen, wie Besucher mit unserer Website interagieren, indem sie Informationen \u00fcber Ihren Besuch sammeln und melden, einschlie\u00dflich der aufgerufenen Seiten und der auf der Website verbrachten Zeit.<\/li>\n<li><strong>Werbe- und Marketing-Cookies.<\/strong> Diese Cookies werden verwendet, um sich an einen Besucher unserer Website zu erinnern, um Anzeigen anzuzeigen, die f\u00fcr Sie relevant und ansprechend sind, auf anderen Websites, sowie um die Anzahl der Anzeigen zu begrenzen. Diese Cookies helfen uns auch, die Wirksamkeit unserer Werbe- oder E-Mail-Marketingkampagnen zu messen. Im Folgenden erfahren Sie mehr dar\u00fcber, wie Sie diese Verwendung von Cookies deaktivieren k\u00f6nnen.<\/li>\n<\/ol>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7d7a6d elementor-widget elementor-widget-heading\" data-id=\"e7d7a6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Wie Sie die Verwendung von Cookies deaktivieren k\u00f6nnen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-deeab6f elementor-widget elementor-widget-text-editor\" data-id=\"deeab6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol>\n \t<li><strong>\u00dcber unser Cookie-Pr\u00e4ferenz-Center.<\/strong> Sie k\u00f6nnen Cookies \u00fcber unser Cookie-Pr\u00e4ferenz-Center hier deaktivieren.<\/li>\n \t<li><strong>\u00dcber Ihren Browser.<\/strong> Sie k\u00f6nnen Ihre Browsereinstellungen so anpassen, dass Ihr Browser alle oder einige Cookies blockiert. Sie k\u00f6nnen auch bereits gesetzte Cookies l\u00f6schen. Bitte beachten Sie, dass unsere Website oder Dienste automatisierte Browsersignale in Bezug auf Tracking-Mechanismen, wie z. B. &#8220;Do Not Track&#8221;-Anweisungen, m\u00f6glicherweise nicht erkennen.<\/li>\n \t<li><strong>Mit jedem unserer Lieferanten individuell.<\/strong> Im Folgenden finden Sie Anbieter mit Werbe- und Marketing-Cookies, die unsere Website verwendet, und einem Link zur Opt-out-Seite jedes Anbieters:<\/li>\n<\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1e6e4c uael-header-sticky-no uael-border-yes elementor-widget elementor-widget-uael-table\" data-id=\"f1e6e4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div itemscope class=\"uael-table-wrapper\" itemtype=\"http:\/\/schema.org\/Table\">\n\t\t<table id=\"uael-table-id-f1e6e4c\" class=\"uael-text-break uael-column-rules uael-table\" data-sort-table=\"no\" data-show-entry=\"no\" data-searchable=\"no\" data-responsive=\"yes\">\n\t\t\t\t<thead>\n\t\t\t\t\t\t\t\t\t\t<tr class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<th data-sort=\"0\" class=\"sort-this elementor-repeater-item-5a4eb6a uael-table-col uael-table-head-cell-text\" scope=\"col\">\n\t\t\t\t\t\t\t<span class=\"sort-style\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Analytische Cookies<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t<\/thead>\n\t\t\t\t<tbody>\n\t\t\t<!-- ROWS -->\n\t\t\t\t\t\t\t\t\t\t<tr data-entry=\"1\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-9678186\" data-title=\"Analytische Cookies\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Adobe Analytics<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-8886f47\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.adobe.com\/privacy\/opt-out.html\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Sammeln von Daten \u00fcber die Nutzung der Website und das Verhalten der Benutzer auf der Website. Adobe Analytics Opt Out <\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"2\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-4f2e9ca\" data-title=\"Analytische Cookies\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Bing Analytics<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-2c2c7cf\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.microsoft.com\/en-us\/privacy\/privacystatement\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Setzt eine eindeutige Benutzer-ID, um zu verfolgen, wie der Benutzer die Website nutzt. Bing Analytics Datenschutzrichtlinie <\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"3\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-0486fd1\" data-title=\"Analytische Cookies\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Google Analytics  <\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-0c111cd\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Google Analytics deaktivieren<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"4\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-94ce4f3\" data-title=\"Analytische Cookies\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Hubspot<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-abd747c\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/legal.hubspot.com\/privacy-policy\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Dieses Cookie verfolgt die Identit\u00e4t eines Besuchers. Es wird an HubSpot bei der Formular\u00fcbermittlung \u00fcbergeben und verwendet, wenn Kontakte dedupliziert werden.  Hubspot Datenschutzrichtlinie<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"5\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-2757de3\" data-title=\"Analytische Cookies\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Microsoft Clarity<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-67c4baa\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/learn.microsoft.com\/en-us\/clarity\/setup-and-installation\/cookie-consent\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Verbindet mehrere Seitenaufrufe eines Benutzers zu einer einzigen Clarity-Sitzungsaufzeichnung. Microsoft Clarity Richtlinie <\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"6\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-2b1944a\" data-title=\"Analytische Cookies\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Outbrain<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-69585b3\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.outbrain.com\/privacy\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Speichert die ID des anonymen Benutzers. Wird verwendet, um Benutzeraktionen wie Klicks auf Empfehlungen zu verfolgen. Outbrain Datenschutzrichtlinie  <\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"7\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-be8484e\" data-title=\"Analytische Cookies\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Rubicon Project<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-877f79c\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.rubicon.com\/privacy-policy\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Wird verwendet, um anonymisierte Benutzerdaten wie IP-Adresse, geografischen Standort, besuchte Websites und angeklickte Anzeigen zu registrieren, mit dem Ziel, die Anzeigenschaltung basierend auf den Bewegungen des Benutzers auf Websites, die dasselbe Anzeigennetzwerk verwenden, zu optimieren. Rubicon Project Datenschutzrichtlinie <\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"8\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-84ba779\" data-title=\"Analytische Cookies\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Vimeo Analytics<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-7c37b17\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vimeo.com\/cookie_policy#:~:text=Cookie%20Basics,as%20analytics%20providers%20and%20advertisers.\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Wird vom Vimeo-Player verwendet, um zu \u00fcberpr\u00fcfen, ob bestimmte Funktionen oder Einstellungen vom Benutzer auf Websites mit eingebetteten Vimeo-Videos ausgew\u00e4hlt wurden. Vimeo Analytics Cookie-Richtlinie <\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"9\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-f5f1436\" data-title=\"Analytische Cookies\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Yandex Metrica<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-8b444b9\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/yandex.com\/support\/metrica\/general\/cookie-usage.html\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Wird von Yandex Metrica zur Identifizierung von Website-Benutzern verwendet. Yandex Metrica Datenschutzrichtlinie <\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t<\/tbody>\n\t<\/table>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3218a15 uael-header-sticky-no uael-border-yes elementor-widget elementor-widget-uael-table\" data-id=\"3218a15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div itemscope class=\"uael-table-wrapper\" itemtype=\"http:\/\/schema.org\/Table\">\n\t\t<table id=\"uael-table-id-3218a15\" class=\"uael-text-break uael-column-rules uael-table\" data-sort-table=\"no\" data-show-entry=\"no\" data-searchable=\"no\" data-responsive=\"yes\">\n\t\t\t\t<thead>\n\t\t\t\t\t\t\t\t\t\t<tr class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<th data-sort=\"0\" class=\"sort-this elementor-repeater-item-d73762d uael-table-col uael-table-head-cell-text\" scope=\"col\">\n\t\t\t\t\t\t\t<span class=\"sort-style\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Werbe-Cookies<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t<\/thead>\n\t\t\t\t<tbody>\n\t\t\t<!-- ROWS -->\n\t\t\t\t\t\t\t\t\t\t<tr data-entry=\"1\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-71fb161\" data-title=\"Werbe-Cookies\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Atlas<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-e0c0b77\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.atlas.net\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Atlas Adserver, verwendet in Verbindung mit Bing-Diensten. Atlas Datenschutzrichtlinie <\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"2\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-69e9f9e\" data-title=\"Werbe-Cookies\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">App Nexus<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-93932f2\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/appnexustech.com\/privacy-policy\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Dieses Cookie geh\u00f6rt App Nexus und wird verwendet, um Online-Werbung zu kaufen, zu verkaufen und zu liefern, einschlie\u00dflich interessenbasierter Werbung, haupts\u00e4chlich durch Echtzeitgebote. App Nexus Datenschutzrichtlinie <\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"3\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-653f053\" data-title=\"Werbe-Cookies\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Bing<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-520fa97\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.microsoft.com\/en-us\/privacy\/privacystatement\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Wird von Bing als eindeutiger Benutzeridentifikator f\u00fcr Benutzer verwendet, die Bing-Anzeigen sehen. Bing Datenschutzrichtlinie <\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"4\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-1c61447\" data-title=\"Werbe-Cookies\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Casale Media<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-4eb26b9\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.casalemedia.com\/#:~:text=indexexchange.com%2F.-,Casale%20Media%20believes%20in%20all%20Internet%20users&#039;%20rights%20to%20privacy,postal%20addresses%2C%20and%20phone%20numbers.\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Persistente Cookies, die von CasaleMedia gesetzt werden, um anonyme Benutzer zu verfolgen und die Daten f\u00fcr zielgerichtete Werbung zu verwenden. Casale Media Datenschutzrichtlinie <\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"5\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-0d15943\" data-title=\"Werbe-Cookies\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Connexity<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-29901ac\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.connexity.com\/privacy-policy\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Ein Sitzungscookie, das verwendet wird, um relevante Anzeigen basierend auf den Interessen eines Benutzers auf einer Website anzuzeigen. Connexity Datenschutzrichtlinie <\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"6\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-c19368f\" data-title=\"Werbe-Cookies\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Facebook<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-3440334\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/help\/568137493302217\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Facebook-Tracking-Pixel, das verwendet wird, um Besucher f\u00fcr personalisierte Werbung zu identifizieren. Einstellungen f\u00fcr Facebook-Werbung<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"7\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-f3d8a65\" data-title=\"Werbe-Cookies\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Google<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-eefbc96\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/support.google.com\/ads\/answer\/2662922?hl=en-GB\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Diese Domain geh\u00f6rt Doubleclick (Google). Wir verwenden Doubleclick, um den Echtzeit-Werbeaustausch zu verwalten.  Google Werbung deaktivieren<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"8\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-072e219\" data-title=\"Werbe-Cookies\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">LinkedIn<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-3b53757\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/psettings\/guest-controls\/retargeting-opt-out\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Diese Cookies sind mit einer B2B-Marketingplattform verbunden, die fr\u00fcher als Bizo bekannt war und jetzt LinkedIn geh\u00f6rt, der Business-Networking-Plattform. Diese Subdomain ist mit den Marketingdiensten von LinkedIn verbunden, die Website-Besitzern Einblicke in die Art der Benutzer auf ihrer Website basierend auf LinkedIn-Profil-Daten erm\u00f6glichen, um das Targeting zu verbessern.  LinkedIn Werbepr\u00e4ferenzen<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"9\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-b5c22ee\" data-title=\"Werbe-Cookies\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Pubmatic<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-c956421\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/pubmatic.com\/legal\/privacy-policy\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Wird von Pubmatic verwendet, um Benutzer-IDs mit denen ihrer Partner (wie Demand-Side-Plattform-Kunden oder anderen Werbetechnologieunternehmen) zu korrelieren. Pubmatic \u00fcbermittelt die in diesem Cookie gespeicherten Informationen an den Partner, wenn dieser erw\u00e4gt, Anzeigen zu kaufen. Dies erm\u00f6glicht dem Partner, bessere Entscheidungen dar\u00fcber zu treffen, ob eine Anzeige einem Website-Besucher angezeigt werden soll. Pubmatic Datenschutzrichtlinie   <\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"10\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-c5a8b3d\" data-title=\"Werbe-Cookies\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Tapad<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-e51bccd\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.tapad.com\/global-privacy-notice\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Wird verwendet, um zu bestimmen, welche Art von Ger\u00e4ten (Smartphones, Tablets, Computer, Fernseher usw.) von einem Benutzer verwendet wird. L\u00e4uft nach 2 Monaten ab. Tapad Datenschutzrichtlinie  <\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"11\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-064616e\" data-title=\"Werbe-Cookies\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Triplelift<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-8ebf95c\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/triplelift.com\/privacy\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\"> Von Triplelift als eindeutige Benutzer-ID gesetzt, um anonyme Informationen \u00fcber die Surfgewohnheiten des Benutzers zu sammeln. Triplelift Datenschutzrichtlinie <\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"12\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-807fb1e\" data-title=\"Werbe-Cookies\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">The Trade Desk<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-08f4b1b\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.adsrvr.org\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Ist ein Drittanbieter-Cookie, das einen einzigartigen, zuf\u00e4llig generierten Wert enth\u00e4lt, der es der Plattform erm\u00f6glicht, Browser und Ger\u00e4te zu unterscheiden. The Trade Desk Opt-Out <\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"13\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-612192f\" data-title=\"Werbe-Cookies\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Yahoo<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-146adb1\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/legal.yahoo.com\/us\/en\/yahoo\/privacy\/index.html\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Cookies, die auf Drittanbieter-Websites und -Apps gesetzt werden. Yahoo Datenschutzrichtlinie <\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t<\/tbody>\n\t<\/table>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64cf42f elementor-widget elementor-widget-text-editor\" data-id=\"64cf42f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>4. <strong>Durch branchenweite Opt-out-Mechanismen.<\/strong>. Verbraucher k\u00f6nnen einen branchenweiten Opt-out-Antrag f\u00fcr interessenbezogene Werbung \u00fcber die Opt-out-Website der Digital Advertising Alliance (DAA) stellen, die unter <a href=\"https:\/\/optout.aboutads.info\/\" target=\"_blank\" rel=\"noopener\">optout.aboutads.info<\/a> oder f\u00fcr EU-Besucher unter <a href=\"https:\/\/youronlinechoices.eu\/\" target=\"_blank\" rel=\"noopener\">https:\/\/youronlinechoices.eu\/<\/a> zu finden ist<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-852ccfe elementor-widget elementor-widget-heading\" data-id=\"852ccfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00c4nderungen an dieser Richtlinie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e0c6f7 elementor-widget elementor-widget-text-editor\" data-id=\"5e0c6f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir behalten uns das Recht vor, diese Richtlinie von Zeit zu Zeit zu \u00fcberarbeiten. \u00dcberpr\u00fcfen Sie es gelegentlich, damit Sie \u00fcber unsere neuesten Praktiken auf dem Laufenden bleiben. Wir geben das Datum des Inkrafttretens der neuesten Version am Anfang jeder Richtlinie an.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f48b7a5 elementor-widget elementor-widget-heading\" data-id=\"f48b7a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kontaktieren Sie uns<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-195c9d6 elementor-widget elementor-widget-text-editor\" data-id=\"195c9d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>F\u00fcr weitere Informationen \u00fcber unsere Verwendung von Cookies kontaktieren Sie uns bitte unter <span style=\"text-decoration: underline;\"><a href=\"mailto:legal@revalizesoftware.com\">legal@revalizesoftware.com<\/a><\/span>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Globaler Cookie-Hinweis von Revalize Wirksamkeitsdatum: 28. Oktober 2024 Revalize, Inc. (&#8220;Revalize&#8221;, &#8220;Wir&#8221;, &#8220;Uns&#8221;, &#8220;Unser&#8221;) verwendet wie viele andere Unternehmen &#8220;Cookies&#8221; und andere Tracking-Technologien (zusammenfassend als &#8220;Tracking-Technologien&#8221; bezeichnet), um unsere Dienste (&#8220;Dienste&#8221;) zu erm\u00f6glichen, zu personalisieren und zu verbessern. In diesem Cookie-Hinweis werden die von uns verwendeten Tracking-Technologien, die Zwecke, f\u00fcr die wir sie verwenden, und [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"parent":17722,"menu_order":88,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"content-type":"","footnotes":""},"class_list":["post-20854","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Globaler Cookie-Hinweis - Revalize<\/title>\n<meta name=\"description\" content=\"Verstehen Sie, wie Revalize Cookies und andere Tracking-Technologien verwendet, um seine Dienste zu personalisieren und zu verbessern.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/revalizesoftware.com\/de\/rechtliches\/globaler-cookie-hinweis\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Globaler Cookie-Hinweis\" \/>\n<meta property=\"og:description\" content=\"Verstehen Sie, wie Revalize Cookies und andere Tracking-Technologien verwendet, um seine Dienste zu personalisieren und zu verbessern.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/revalizesoftware.com\/de\/rechtliches\/globaler-cookie-hinweis\/\" \/>\n<meta property=\"og:site_name\" content=\"Revalize\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revalize\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-12T17:05:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@revalize\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/revalizesoftware.com\\\/de\\\/rechtliches\\\/globaler-cookie-hinweis\\\/\",\"url\":\"https:\\\/\\\/revalizesoftware.com\\\/de\\\/rechtliches\\\/globaler-cookie-hinweis\\\/\",\"name\":\"Globaler Cookie-Hinweis - Revalize\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/revalizesoftware.com\\\/de\\\/#website\"},\"datePublished\":\"2023-05-25T22:36:00+00:00\",\"dateModified\":\"2025-03-12T17:05:45+00:00\",\"description\":\"Verstehen Sie, wie Revalize Cookies und andere Tracking-Technologien verwendet, um seine Dienste zu personalisieren und zu verbessern.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/revalizesoftware.com\\\/de\\\/rechtliches\\\/globaler-cookie-hinweis\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/revalizesoftware.com\\\/de\\\/rechtliches\\\/globaler-cookie-hinweis\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/revalizesoftware.com\\\/de\\\/rechtliches\\\/globaler-cookie-hinweis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/revalizesoftware.com\\\/de\\\/revalize\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Revalize Rechtliches\",\"item\":\"https:\\\/\\\/revalizesoftware.com\\\/de\\\/rechtliches\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Globaler Cookie-Hinweis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/revalizesoftware.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/revalizesoftware.com\\\/de\\\/\",\"name\":\"Revalize\",\"description\":\"Great Starts with Revalize\",\"publisher\":{\"@id\":\"https:\\\/\\\/revalizesoftware.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/revalizesoftware.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/revalizesoftware.com\\\/de\\\/#organization\",\"name\":\"Revalize\",\"url\":\"https:\\\/\\\/revalizesoftware.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/revalizesoftware.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/revalizesoftware.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/revalize-logo.png\",\"contentUrl\":\"https:\\\/\\\/revalizesoftware.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/revalize-logo.png\",\"width\":976,\"height\":423,\"caption\":\"Revalize\"},\"image\":{\"@id\":\"https:\\\/\\\/revalizesoftware.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/revalize\\\/\",\"https:\\\/\\\/x.com\\\/revalize\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/revalize\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Globaler Cookie-Hinweis - Revalize","description":"Verstehen Sie, wie Revalize Cookies und andere Tracking-Technologien verwendet, um seine Dienste zu personalisieren und zu verbessern.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/revalizesoftware.com\/de\/rechtliches\/globaler-cookie-hinweis\/","og_locale":"de_DE","og_type":"article","og_title":"Globaler Cookie-Hinweis","og_description":"Verstehen Sie, wie Revalize Cookies und andere Tracking-Technologien verwendet, um seine Dienste zu personalisieren und zu verbessern.","og_url":"https:\/\/revalizesoftware.com\/de\/rechtliches\/globaler-cookie-hinweis\/","og_site_name":"Revalize","article_publisher":"https:\/\/www.facebook.com\/revalize\/","article_modified_time":"2025-03-12T17:05:45+00:00","twitter_card":"summary_large_image","twitter_site":"@revalize","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/revalizesoftware.com\/de\/rechtliches\/globaler-cookie-hinweis\/","url":"https:\/\/revalizesoftware.com\/de\/rechtliches\/globaler-cookie-hinweis\/","name":"Globaler Cookie-Hinweis - Revalize","isPartOf":{"@id":"https:\/\/revalizesoftware.com\/de\/#website"},"datePublished":"2023-05-25T22:36:00+00:00","dateModified":"2025-03-12T17:05:45+00:00","description":"Verstehen Sie, wie Revalize Cookies und andere Tracking-Technologien verwendet, um seine Dienste zu personalisieren und zu verbessern.","breadcrumb":{"@id":"https:\/\/revalizesoftware.com\/de\/rechtliches\/globaler-cookie-hinweis\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/revalizesoftware.com\/de\/rechtliches\/globaler-cookie-hinweis\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/revalizesoftware.com\/de\/rechtliches\/globaler-cookie-hinweis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/revalizesoftware.com\/de\/revalize\/"},{"@type":"ListItem","position":2,"name":"Revalize Rechtliches","item":"https:\/\/revalizesoftware.com\/de\/rechtliches\/"},{"@type":"ListItem","position":3,"name":"Globaler Cookie-Hinweis"}]},{"@type":"WebSite","@id":"https:\/\/revalizesoftware.com\/de\/#website","url":"https:\/\/revalizesoftware.com\/de\/","name":"Revalize","description":"Great Starts with Revalize","publisher":{"@id":"https:\/\/revalizesoftware.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/revalizesoftware.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/revalizesoftware.com\/de\/#organization","name":"Revalize","url":"https:\/\/revalizesoftware.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/revalizesoftware.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/revalizesoftware.com\/wp-content\/uploads\/2021\/05\/revalize-logo.png","contentUrl":"https:\/\/revalizesoftware.com\/wp-content\/uploads\/2021\/05\/revalize-logo.png","width":976,"height":423,"caption":"Revalize"},"image":{"@id":"https:\/\/revalizesoftware.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/revalize\/","https:\/\/x.com\/revalize","https:\/\/www.linkedin.com\/company\/revalize\/"]}]}},"_links":{"self":[{"href":"https:\/\/revalizesoftware.com\/de\/wp-json\/wp\/v2\/pages\/20854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revalizesoftware.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/revalizesoftware.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/revalizesoftware.com\/de\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/revalizesoftware.com\/de\/wp-json\/wp\/v2\/comments?post=20854"}],"version-history":[{"count":0,"href":"https:\/\/revalizesoftware.com\/de\/wp-json\/wp\/v2\/pages\/20854\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/revalizesoftware.com\/de\/wp-json\/wp\/v2\/pages\/17722"}],"wp:attachment":[{"href":"https:\/\/revalizesoftware.com\/de\/wp-json\/wp\/v2\/media?parent=20854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}